{"id":57,"date":"2021-08-13T22:11:19","date_gmt":"2021-08-13T20:11:19","guid":{"rendered":"https:\/\/golfecoledelair.fr\/?page_id=57"},"modified":"2026-04-18T22:34:32","modified_gmt":"2026-04-18T20:34:32","slug":"competitions-militaires","status":"publish","type":"page","link":"https:\/\/golfecoledelair.fr\/index.php\/competitions-militaires\/","title":{"rendered":"Coupe de l&rsquo;\u00c9cole de l&rsquo;Air et de l&rsquo;Espace"},"content":{"rendered":"\n<figure class=\"wp-block-table has-normal-font-size\"><table class=\"has-background\" style=\"background:radial-gradient(rgb(255,245,203) 0%,rgb(182,227,212) 13%,rgb(51,167,181) 100%)\"><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\"><br><img decoding=\"async\" width=\"400\" height=\"372\" class=\"wp-image-5854\" style=\"width: 400px;\" src=\"https:\/\/golfecoledelair.fr\/wp-content\/uploads\/2024\/04\/Logo-EAE-centre-2.png\" alt=\"\" srcset=\"https:\/\/golfecoledelair.fr\/wp-content\/uploads\/2024\/04\/Logo-EAE-centre-2.png 1450w, https:\/\/golfecoledelair.fr\/wp-content\/uploads\/2024\/04\/Logo-EAE-centre-2-300x279.png 300w, https:\/\/golfecoledelair.fr\/wp-content\/uploads\/2024\/04\/Logo-EAE-centre-2-1024x953.png 1024w, https:\/\/golfecoledelair.fr\/wp-content\/uploads\/2024\/04\/Logo-EAE-centre-2-768x715.png 768w, https:\/\/golfecoledelair.fr\/wp-content\/uploads\/2024\/04\/Logo-EAE-centre-2-322x300.png 322w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><br><strong><a href=\"https:\/\/golfecoledelair.fr\/index.php\/coupe-de-lecole-de-lair-et-de-lespace-2026\/\" title=\"\">Coupe EAE 2026<\/a><br><\/strong><br><a href=\"https:\/\/golfecoledelair.fr\/index.php\/coupe-de-lecole-de-lair-et-de-lespace-2025\/\" title=\"\"><strong>Coupe EAE 2025<\/strong><\/a><br><br><a href=\"https:\/\/golfecoledelair.fr\/index.php\/coupe-de-lecole-de-lair-et-de-lespace-2024\/\" title=\"\"><strong>Coupe EAE 2024<\/strong><\/a><br><br><a href=\"https:\/\/golfecoledelair.fr\/index.php\/coupe-de-lecole-de-lair-et-de-lespace-2023\/\" title=\"\"><strong>Coupe EAE 2023<\/strong><\/a><br><br><strong><a href=\"https:\/\/golfecoledelair.fr\/index.php\/coupe-de-lecole-de-lair-2022\/\" title=\"\">Coupe EA 2022<\/a><\/strong><\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Coupe EAE 2026Coupe EAE 2025 Coupe EAE 2024 Coupe EAE 2023 Coupe EA 2022<\/p>\n","protected":false},"author":1,"featured_media":10126,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-57","page","type-page","status-publish","has-post-thumbnail","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/golfecoledelair.fr\/index.php\/competitions-militaires\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"fr_FR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Golf de l&#039;\u00c9cole de l&#039;Air et de l&#039;Espace - Jouer au golf sur la Base a\u00e9rienne 701\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Coupe de l\u2019\u00c9cole de l\u2019Air et de l\u2019Espace - Golf de l&#039;\u00c9cole de l&#039;Air et de l&#039;Espace\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/golfecoledelair.fr\/index.php\/competitions-militaires\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/golfecoledelair.fr\/wp-content\/uploads\/2021\/08\/logo-golf.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/golfecoledelair.fr\/wp-content\/uploads\/2021\/08\/logo-golf.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2021-08-13T20:11:19+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-04-18T20:34:32+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Coupe de l\u2019\u00c9cole de l\u2019Air et de l\u2019Espace - Golf de l&#039;\u00c9cole de l&#039;Air et de l&#039;Espace\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/golfecoledelair.fr\/wp-content\/uploads\/2021\/08\/logo-golf.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/golfecoledelair.fr\\\/index.php\\\/competitions-militaires\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/golfecoledelair.fr#listItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/golfecoledelair.fr\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/golfecoledelair.fr\\\/index.php\\\/competitions-militaires\\\/#listItem\",\"name\":\"Coupe de l&rsquo;\\u00c9cole de l&rsquo;Air et de l&rsquo;Espace\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/golfecoledelair.fr\\\/index.php\\\/competitions-militaires\\\/#listItem\",\"position\":2,\"name\":\"Coupe de l&rsquo;\\u00c9cole de l&rsquo;Air et de l&rsquo;Espace\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/golfecoledelair.fr#listItem\",\"name\":\"Accueil\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/golfecoledelair.fr\\\/#organization\",\"name\":\"Golf de l'\\u00c9cole de l'Air et de l'Espace\",\"description\":\"Jouer au golf sur la Base a\\u00e9rienne 701\",\"url\":\"https:\\\/\\\/golfecoledelair.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/golfecoledelair.fr\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/logo-golf.png\",\"@id\":\"https:\\\/\\\/golfecoledelair.fr\\\/index.php\\\/competitions-militaires\\\/#organizationLogo\",\"width\":460,\"height\":458},\"image\":{\"@id\":\"https:\\\/\\\/golfecoledelair.fr\\\/index.php\\\/competitions-militaires\\\/#organizationLogo\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/golfecoledelair.fr\\\/index.php\\\/competitions-militaires\\\/#webpage\",\"url\":\"https:\\\/\\\/golfecoledelair.fr\\\/index.php\\\/competitions-militaires\\\/\",\"name\":\"Coupe de l\\u2019\\u00c9cole de l\\u2019Air et de l\\u2019Espace - Golf de l'\\u00c9cole de l'Air et de l'Espace\",\"inLanguage\":\"fr-FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/golfecoledelair.fr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/golfecoledelair.fr\\\/index.php\\\/competitions-militaires\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/golfecoledelair.fr\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Coupe-EAE-0-G18-a.jpg\",\"@id\":\"https:\\\/\\\/golfecoledelair.fr\\\/index.php\\\/competitions-militaires\\\/#mainImage\",\"width\":2560,\"height\":960},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/golfecoledelair.fr\\\/index.php\\\/competitions-militaires\\\/#mainImage\"},\"datePublished\":\"2021-08-13T22:11:19+02:00\",\"dateModified\":\"2026-04-18T22:34:32+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/golfecoledelair.fr\\\/#website\",\"url\":\"https:\\\/\\\/golfecoledelair.fr\\\/\",\"name\":\"Golf de l'\\u00c9cole de l'Air et de l'Espace\",\"description\":\"Jouer au golf sur la Base a\\u00e9rienne 701\",\"inLanguage\":\"fr-FR\",\"publisher\":{\"@id\":\"https:\\\/\\\/golfecoledelair.fr\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Coupe de l\u2019\u00c9cole de l\u2019Air et de l\u2019Espace - Golf de l'\u00c9cole de l'Air et de l'Espace","description":"","canonical_url":"https:\/\/golfecoledelair.fr\/index.php\/competitions-militaires\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/golfecoledelair.fr\/index.php\/competitions-militaires\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/golfecoledelair.fr#listItem","position":1,"name":"Accueil","item":"https:\/\/golfecoledelair.fr","nextItem":{"@type":"ListItem","@id":"https:\/\/golfecoledelair.fr\/index.php\/competitions-militaires\/#listItem","name":"Coupe de l&rsquo;\u00c9cole de l&rsquo;Air et de l&rsquo;Espace"}},{"@type":"ListItem","@id":"https:\/\/golfecoledelair.fr\/index.php\/competitions-militaires\/#listItem","position":2,"name":"Coupe de l&rsquo;\u00c9cole de l&rsquo;Air et de l&rsquo;Espace","previousItem":{"@type":"ListItem","@id":"https:\/\/golfecoledelair.fr#listItem","name":"Accueil"}}]},{"@type":"Organization","@id":"https:\/\/golfecoledelair.fr\/#organization","name":"Golf de l'\u00c9cole de l'Air et de l'Espace","description":"Jouer au golf sur la Base a\u00e9rienne 701","url":"https:\/\/golfecoledelair.fr\/","logo":{"@type":"ImageObject","url":"https:\/\/golfecoledelair.fr\/wp-content\/uploads\/2021\/08\/logo-golf.png","@id":"https:\/\/golfecoledelair.fr\/index.php\/competitions-militaires\/#organizationLogo","width":460,"height":458},"image":{"@id":"https:\/\/golfecoledelair.fr\/index.php\/competitions-militaires\/#organizationLogo"}},{"@type":"WebPage","@id":"https:\/\/golfecoledelair.fr\/index.php\/competitions-militaires\/#webpage","url":"https:\/\/golfecoledelair.fr\/index.php\/competitions-militaires\/","name":"Coupe de l\u2019\u00c9cole de l\u2019Air et de l\u2019Espace - Golf de l'\u00c9cole de l'Air et de l'Espace","inLanguage":"fr-FR","isPartOf":{"@id":"https:\/\/golfecoledelair.fr\/#website"},"breadcrumb":{"@id":"https:\/\/golfecoledelair.fr\/index.php\/competitions-militaires\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/golfecoledelair.fr\/wp-content\/uploads\/2026\/04\/Coupe-EAE-0-G18-a.jpg","@id":"https:\/\/golfecoledelair.fr\/index.php\/competitions-militaires\/#mainImage","width":2560,"height":960},"primaryImageOfPage":{"@id":"https:\/\/golfecoledelair.fr\/index.php\/competitions-militaires\/#mainImage"},"datePublished":"2021-08-13T22:11:19+02:00","dateModified":"2026-04-18T22:34:32+02:00"},{"@type":"WebSite","@id":"https:\/\/golfecoledelair.fr\/#website","url":"https:\/\/golfecoledelair.fr\/","name":"Golf de l'\u00c9cole de l'Air et de l'Espace","description":"Jouer au golf sur la Base a\u00e9rienne 701","inLanguage":"fr-FR","publisher":{"@id":"https:\/\/golfecoledelair.fr\/#organization"}}]},"og:locale":"fr_FR","og:site_name":"Golf de l'\u00c9cole de l'Air et de l'Espace - Jouer au golf sur la Base a\u00e9rienne 701","og:type":"article","og:title":"Coupe de l\u2019\u00c9cole de l\u2019Air et de l\u2019Espace - Golf de l'\u00c9cole de l'Air et de l'Espace","og:url":"https:\/\/golfecoledelair.fr\/index.php\/competitions-militaires\/","og:image":"https:\/\/golfecoledelair.fr\/wp-content\/uploads\/2021\/08\/logo-golf.png","og:image:secure_url":"https:\/\/golfecoledelair.fr\/wp-content\/uploads\/2021\/08\/logo-golf.png","article:published_time":"2021-08-13T20:11:19+00:00","article:modified_time":"2026-04-18T20:34:32+00:00","twitter:card":"summary","twitter:title":"Coupe de l\u2019\u00c9cole de l\u2019Air et de l\u2019Espace - Golf de l'\u00c9cole de l'Air et de l'Espace","twitter:image":"https:\/\/golfecoledelair.fr\/wp-content\/uploads\/2021\/08\/logo-golf.png"},"aioseo_meta_data":{"post_id":"57","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":{"id":"aioseo-web-page-636d867f8bb66","slug":"web-page","graphName":"WebPage","label":"Web Page","properties":{"type":"WebPage","name":"","description":""}}},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"},\"blockGraphs\":[]}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2021-08-13 20:11:19","updated":"2026-04-18 20:35:10","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/golfecoledelair.fr\" title=\"Accueil\">Accueil<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tCoupe de l\u2019\u00c9cole de l\u2019Air et de l\u2019Espace\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Accueil","link":"https:\/\/golfecoledelair.fr"},{"label":"Coupe de l&rsquo;\u00c9cole de l&rsquo;Air et de l&rsquo;Espace","link":"https:\/\/golfecoledelair.fr\/index.php\/competitions-militaires\/"}],"_links":{"self":[{"href":"https:\/\/golfecoledelair.fr\/index.php\/wp-json\/wp\/v2\/pages\/57","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/golfecoledelair.fr\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/golfecoledelair.fr\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/golfecoledelair.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/golfecoledelair.fr\/index.php\/wp-json\/wp\/v2\/comments?post=57"}],"version-history":[{"count":142,"href":"https:\/\/golfecoledelair.fr\/index.php\/wp-json\/wp\/v2\/pages\/57\/revisions"}],"predecessor-version":[{"id":10059,"href":"https:\/\/golfecoledelair.fr\/index.php\/wp-json\/wp\/v2\/pages\/57\/revisions\/10059"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/golfecoledelair.fr\/index.php\/wp-json\/wp\/v2\/media\/10126"}],"wp:attachment":[{"href":"https:\/\/golfecoledelair.fr\/index.php\/wp-json\/wp\/v2\/media?parent=57"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}